{"id":2312,"date":"2016-07-20T17:39:33","date_gmt":"2016-07-20T17:39:33","guid":{"rendered":"http:\/\/themenectar.com\/demo\/salient-product\/?page_id=2"},"modified":"2025-11-17T01:05:47","modified_gmt":"2025-11-17T01:05:47","slug":"sample-page","status":"publish","type":"page","link":"https:\/\/geoexcon.com\/","title":{"rendered":"Home &#8211; Geoexcon soluciones maquinaria y equipos"},"content":{"rendered":"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#03212d\u00bb video_bg=\u00bbuse_video\u00bb video_mp4=\u00bbhttp:\/\/geoexcon.com\/wp-content\/uploads\/2025\/11\/Geoexcon-maquinaria.mp4&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb8%\u00bb bottom_padding=\u00bb8%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb id=\u00bbintro\u00bb row_name=\u00bbGeoexcon\u00bb color_overlay=\u00bb#5c6971&#8243; overlay_strength=\u00bb0.5&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbtop-bottom\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb20&#8243;][nectar_animated_title heading_tag=\u00bbh6&#8243; style=\u00bbcolor-strip-reveal\u00bb color=\u00bbAccent-Color\u00bb text_color=\u00bb#000000&#8243; text=\u00bbGeoexcon\u00bb][split_line_heading animation_type=\u00bbdefault\u00bb]\n<h1>Incrementa la productividad de tus proyectos<\/h1>\n[\/split_line_heading][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb delay=\u00bb500&#8243;][vc_column_text css=\u00bb.vc_custom_1625944836754{padding-right: 50px !important;}\u00bb]Soluciones en equipos y maquinaria con garant\u00eda de responsabilidad, cumplimiento y confiabilidad.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb delay=\u00bb700&#8243;][nectar_btn size=\u00bbjumbo\u00bb button_style=\u00bbregular\u00bb button_color_2=\u00bbAccent-Color\u00bb color_override=\u00bb#fcd200&#8243; solid_text_color_override=\u00bb#000000&#8243; icon_family=\u00bbdefault_arrow\u00bb url=\u00bb#Sobre-Nosotros\u00bb text=\u00bbCon\u00f3cenos\u00bb margin_top=\u00bb5&#8243; css_animation=\u00bbbounce\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#6a6b6f\u00bb bg_image=\u00bb2396&#8243; bg_position=\u00bbleft top\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb bottom_padding=\u00bb5%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb id=\u00bbSobre-Nosotros\u00bb row_name=\u00bbSobre Nosotros\u00bb color_overlay=\u00bb#0e6093&#8243; overlay_strength=\u00bb0.5&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_cascading_images image_1_bg_color=\u00bb#fcd200&#8243; image_1_offset_x_sign=\u00bb+\u00bb image_1_offset_x=\u00bb0%\u00bb image_1_offset_y_sign=\u00bb+\u00bb image_1_offset_y=\u00bb0%\u00bb image_1_rotate_sign=\u00bb+\u00bb image_1_rotate=\u00bbnone\u00bb image_1_scale=\u00bb1&#8243; image_1_animation=\u00bbGrow In\u00bb image_1_padding=\u00bbauto\u00bb image_1_box_shadow=\u00bbnone\u00bb image_1_max_width_desktop=\u00bb100%\u00bb image_1_max_width_mobile=\u00bb100%\u00bb image_1_image_width_mobile=\u00bbdefault\u00bb image_2_url=\u00bb2381&#8243; image_2_offset_x_sign=\u00bb+\u00bb image_2_offset_x=\u00bb10%\u00bb image_2_offset_y_sign=\u00bb+\u00bb image_2_offset_y=\u00bb15%\u00bb image_2_rotate_sign=\u00bb+\u00bb image_2_rotate=\u00bbnone\u00bb image_2_scale=\u00bb1&#8243; image_2_animation=\u00bbGrow In\u00bb image_2_padding=\u00bbauto\u00bb image_2_box_shadow=\u00bbx_large_depth\u00bb image_2_max_width_desktop=\u00bb100%\u00bb image_2_max_width_mobile=\u00bb100%\u00bb image_2_image_width_mobile=\u00bbdefault\u00bb image_3_offset_x_sign=\u00bb+\u00bb image_3_offset_x=\u00bb0%\u00bb image_3_offset_y_sign=\u00bb+\u00bb image_3_offset_y=\u00bb0%\u00bb image_3_rotate_sign=\u00bb+\u00bb image_3_rotate=\u00bbnone\u00bb image_3_scale=\u00bb1&#8243; image_3_animation=\u00bbFade In\u00bb image_3_padding=\u00bbauto\u00bb image_3_box_shadow=\u00bbnone\u00bb image_3_max_width_desktop=\u00bb100%\u00bb image_3_max_width_mobile=\u00bb100%\u00bb image_3_image_width_mobile=\u00bbdefault\u00bb image_4_offset_x_sign=\u00bb+\u00bb image_4_offset_x=\u00bb0%\u00bb image_4_offset_y_sign=\u00bb+\u00bb image_4_offset_y=\u00bb0%\u00bb image_4_rotate_sign=\u00bb+\u00bb image_4_rotate=\u00bbnone\u00bb image_4_scale=\u00bb1&#8243; image_4_animation=\u00bbFade In\u00bb image_4_padding=\u00bbauto\u00bb image_4_box_shadow=\u00bbnone\u00bb image_4_max_width_desktop=\u00bb100%\u00bb image_4_max_width_mobile=\u00bb100%\u00bb image_4_image_width_mobile=\u00bbdefault\u00bb element_sizing=\u00bbdefault\u00bb image_loading=\u00bbdefault\u00bb border_radius=\u00bbnone\u00bb overflow=\u00bbvisible\u00bb][\/vc_column][vc_column column_padding=\u00bbpadding-4-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text]\n<h2><strong>Sobre Nosotros<\/strong><\/h2>\n[\/vc_column_text][vc_column_text css=\u00bb.vc_custom_1626276551541{margin-top: 20px !important;}\u00bb]En Geoexcon ayudamos a <strong>personas, empresas constructoras y mineras<\/strong> que requieren <strong>maquinaria pesada, equipos y personal calificado<\/strong> para la ejecuci\u00f3n de sus proyectos, optimizando tiempos e incrementando la productividad t\u00e9cnica y financiera con una excelente relaci\u00f3n calidad-precio.<\/p>\n<p>Contamos con una amplia experiencia en la planeaci\u00f3n y ejecuci\u00f3n de excavaciones a m\u00e1quina de todo tipo.<\/p>\n<h3><strong>Nuestro servicio va mas all\u00e1 de alquilar un equipo o maquinaria, nos especializamos en adecuar las unidades de acuerdo al requerimiento de cada cliente.<\/strong><\/h3>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#ffffff\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb bottom_padding=\u00bb5%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb id=\u00bbGarantia\u00bb row_name=\u00bbGarantia\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbpadding-11-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbleft-right\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb centered_text=\u00bbtrue\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb.vc_custom_1626195795141{margin-top: 50px !important;margin-bottom: 15px !important;}\u00bb]\n<h2>Garant\u00eda Geoexcon<\/h2>\n<h4><span style=\"color: #999999;\">Gana tranquilidad, ahorra tiempo y optimiza el recurso t\u00e9cnico y financiero.<\/span><\/h4>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_image_with_hotspots image=\u00bb2349&#8243; preview=\u00bbhttp:\/\/geoexcon.com\/wp-content\/uploads\/2021\/07\/Banner-Fondo-Geoexcon-5.jpg\u00bb color_1=\u00bbExtra-Color-2&#8243; hotspot_icon=\u00bbplus_sign\u00bb tooltip=\u00bbhover\u00bb tooltip_shadow=\u00bblarge_depth\u00bb animation=\u00bbtrue\u00bb][nectar_hotspot left=\u00bb9.48456%\u00bb top=\u00bb44.38%\u00bb position=\u00bbbottom\u00bb]Nuestro soporte t\u00e9cnico constante proporciona un servicio de eficiencia y calidad a nuestros equipos y maquinaria dentro de su obra.[\/nectar_hotspot][nectar_hotspot left=\u00bb64.4859%\u00bb top=\u00bb50.9424%\u00bb position=\u00bbbottom\u00bb]Personal certificado, capacitado y siempre disponible.[\/nectar_hotspot][nectar_hotspot left=\u00bb78.3006%\u00bb top=\u00bb13.0816%\u00bb position=\u00bbbottom\u00bb]Contamos con garant\u00edas de buen estado en todo nuestro equipo, el modelo no supera los 5 a\u00f1os de uso y hacemos mantenimientos preventivos constantes.[\/nectar_hotspot][nectar_hotspot left=\u00bb33.9211%\u00bb top=\u00bb37.7928%\u00bb position=\u00bbbottom\u00bb]Tiempo programado de entregas y cumplimiento en los contratos ejecutados.[\/nectar_hotspot][nectar_hotspot left=\u00bb53.8676%\u00bb top=\u00bb87.5303%\u00bb position=\u00bbtop\u00bb]Trabajamos con las marcas mas reconocidas y con garant\u00eda de calidad en el mercado.[\/nectar_hotspot][\/nectar_image_with_hotspots][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#282828&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb4%\u00bb bottom_padding=\u00bb4%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb id=\u00bbServicios\u00bb row_name=\u00bbServicios\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbtop-bottom\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_animated_title heading_tag=\u00bbh6&#8243; style=\u00bbcolor-strip-reveal\u00bb color=\u00bbAccent-Color\u00bb text_color=\u00bb#000000&#8243; text=\u00bbProductos y Servicios\u00bb][vc_column_text]Nuestros servicios son siempre supervisados y ejecutados por especialistas en cada \u00e1rea, lo que garantiza el resultado esperado y asegura el cumplimiento en tiempo y forma de los contratos ejecutados.[\/vc_column_text][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][fancy_box box_style=\u00bbcolor_box_basic\u00bb icon_family=\u00bbfontawesome\u00bb image_url=\u00bb2368&#8243; content_color=\u00bb#000000&#8243; box_color_opacity=\u00bb0.6&#8243; box_alignment=\u00bbcenter\u00bb border_radius=\u00bbdefault\u00bb image_loading=\u00bbdefault\u00bb icon_fontawesome=\u00bbfa fa-check-square-o\u00bb icon_size=\u00bb20&#8243; min_height=\u00bb50&#8243;]<strong>Ejecutamos demoliciones y excavaciones<\/strong><\/p>\n[\/fancy_box][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][fancy_box box_style=\u00bbcolor_box_basic\u00bb icon_family=\u00bbfontawesome\u00bb image_url=\u00bb2368&#8243; content_color=\u00bb#000000&#8243; box_color_opacity=\u00bb0.7&#8243; box_alignment=\u00bbcenter\u00bb border_radius=\u00bbdefault\u00bb image_loading=\u00bbdefault\u00bb icon_fontawesome=\u00bbfa fa-check-square-o\u00bb icon_size=\u00bb20&#8243; min_height=\u00bb50&#8243;]<b>Trabajo en obras civiles<\/b><\/p>\n<p>&nbsp;<\/p>\n[\/fancy_box][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][fancy_box box_style=\u00bbcolor_box_basic\u00bb icon_family=\u00bbfontawesome\u00bb image_url=\u00bb2368&#8243; content_color=\u00bb#000000&#8243; box_color_opacity=\u00bb0.7&#8243; box_alignment=\u00bbcenter\u00bb border_radius=\u00bbdefault\u00bb image_loading=\u00bbdefault\u00bb icon_fontawesome=\u00bbfa fa-check-square-o\u00bb icon_size=\u00bb20&#8243; min_height=\u00bb50&#8243; css=\u00bb.vc_custom_1626201254343{padding-bottom: 10px !important;}\u00bb]<strong>Explotaci\u00f3n minera<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n[\/fancy_box][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][fancy_box box_style=\u00bbcolor_box_basic\u00bb icon_family=\u00bbfontawesome\u00bb image_url=\u00bb2368&#8243; content_color=\u00bb#000000&#8243; box_color_opacity=\u00bb0.7&#8243; box_alignment=\u00bbcenter\u00bb border_radius=\u00bbdefault\u00bb image_loading=\u00bbdefault\u00bb icon_fontawesome=\u00bbfa fa-check-square-o\u00bb icon_size=\u00bb20&#8243; min_height=\u00bb50&#8243;]<strong>Acondicionamiento y movimiento de terrenos.<\/strong>[\/fancy_box][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][fancy_box box_style=\u00bbcolor_box_basic\u00bb icon_family=\u00bbfontawesome\u00bb image_url=\u00bb2368&#8243; content_color=\u00bb#000000&#8243; box_color_opacity=\u00bb0.7&#8243; box_alignment=\u00bbcenter\u00bb border_radius=\u00bbdefault\u00bb image_loading=\u00bbdefault\u00bb icon_fontawesome=\u00bbfa fa-check-square-o\u00bb icon_size=\u00bb20&#8243; min_height=\u00bb50&#8243;]<strong>Movimiento de residuos de construcci\u00f3n y demoliciones.<\/strong>[\/fancy_box][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][fancy_box box_style=\u00bbcolor_box_basic\u00bb icon_family=\u00bbfontawesome\u00bb image_url=\u00bb2368&#8243; content_color=\u00bb#000000&#8243; box_color_opacity=\u00bb0.7&#8243; box_alignment=\u00bbcenter\u00bb border_radius=\u00bbdefault\u00bb image_loading=\u00bbdefault\u00bb icon_fontawesome=\u00bbfa fa-check-square-o\u00bb icon_size=\u00bb20&#8243; min_height=\u00bb50&#8243;]<strong>Alquiler de maquinaria y equipos<\/strong><\/p>\n<p>&nbsp;<\/p>\n[\/fancy_box][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#282e34&#8243; bg_image=\u00bb2346&#8243; bg_position=\u00bbleft top\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb bottom_padding=\u00bb5%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb id=\u00bbMaquinaria-Equipos\u00bb row_name=\u00bbMaquinaria y Equipos\u00bb color_overlay=\u00bb#232323&#8243; overlay_strength=\u00bb0.8&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbpadding-4-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_animated_title heading_tag=\u00bbh6&#8243; style=\u00bbcolor-strip-reveal\u00bb color=\u00bbAccent-Color\u00bb text_color=\u00bb#000000&#8243; text=\u00bbEquipos y Maquinaria\u00bb]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-cog\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"default\" data-alignment=\"left\"> \n<ul>\n<li><strong>Minicargadores<\/strong><\/li>\n<li><strong>Miniexcavadoras<\/strong><\/li>\n<li><strong>Retroexcavadoras<\/strong><\/li>\n<li><strong>Pajaritas<\/strong><\/li>\n<li><strong>Excavadoras 4 -6- 8-12 20- 30- 35 -38 toneladas<\/strong><\/li>\n<li><strong>Bulldozer<\/strong><\/li>\n<li><strong>Vibro compactador<\/strong><\/li>\n<\/ul>\n <\/div>[nectar_animated_title heading_tag=\u00bbh6&#8243; style=\u00bbcolor-strip-reveal\u00bb color=\u00bbAccent-Color\u00bb text_color=\u00bb#000000&#8243; text=\u00bbVolquetas\u00bb]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-cog\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"default\" data-alignment=\"left\"> \n<ul>\n<li><strong>Sencilla<\/strong><\/li>\n<li><strong>Doble troque<\/strong><\/li>\n<li><strong>Ba\u00f1eras<\/strong><\/li>\n<\/ul>\n <\/div>[nectar_btn size=\u00bbjumbo\u00bb open_new_tab=\u00bbtrue\u00bb button_style=\u00bbregular\u00bb button_color_2=\u00bbAccent-Color\u00bb color_override=\u00bb#fcd200&#8243; solid_text_color_override=\u00bb#000000&#8243; icon_family=\u00bbdefault_arrow\u00bb url=\u00bbhttps:\/\/wa.link\/jcxq2l\u00bb text=\u00bbQuiero Cotizar\u00bb margin_top=\u00bb5&#8243; css_animation=\u00bbbounce\u00bb][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_gallery type=\u00bbflickity_style\u00bb images=\u00bb2454,2451,2459,2453,2458,2455,2456,2452&#8243; flickity_spacing=\u00bbdefault\u00bb flickity_controls=\u00bbnext_prev_arrows_overlaid\u00bb flickity_overflow=\u00bbhidden\u00bb flickity_wrap_around=\u00bbwrap\u00bb flickity_desktop_columns=\u00bb1&#8243; flickity_small_desktop_columns=\u00bb1&#8243; flickity_tablet_columns=\u00bb1&#8243; flickity_box_shadow=\u00bbnone\u00bb image_loading=\u00bbdefault\u00bb onclick=\u00bblink_image\u00bb img_size=\u00bb680&#215;680&#8243;][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#6a6b6f\u00bb video_bg=\u00bbuse_video\u00bb video_mp4=\u00bbhttp:\/\/geoexcon.com\/wp-content\/uploads\/2025\/11\/GEOEXCON-MOVIMIENTO-TIERRA.mp4&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb bottom_padding=\u00bb5%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb id=\u00bbmarcas\u00bb row_name=\u00bbMarcas\u00bb color_overlay=\u00bb#0e6093&#8243; overlay_strength=\u00bb0.5&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_cascading_images image_1_bg_color=\u00bb#fcd200&#8243; image_1_offset_x_sign=\u00bb+\u00bb image_1_offset_x=\u00bb0%\u00bb image_1_offset_y_sign=\u00bb+\u00bb image_1_offset_y=\u00bb0%\u00bb image_1_rotate_sign=\u00bb+\u00bb image_1_rotate=\u00bbnone\u00bb image_1_scale=\u00bb1&#8243; image_1_animation=\u00bbGrow In\u00bb image_1_padding=\u00bbauto\u00bb image_1_box_shadow=\u00bbnone\u00bb image_1_max_width_desktop=\u00bb100%\u00bb image_1_max_width_mobile=\u00bb100%\u00bb image_1_image_width_mobile=\u00bbdefault\u00bb image_2_url=\u00bb2353&#8243; image_2_offset_x_sign=\u00bb+\u00bb image_2_offset_x=\u00bb10%\u00bb image_2_offset_y_sign=\u00bb+\u00bb image_2_offset_y=\u00bb15%\u00bb image_2_rotate_sign=\u00bb+\u00bb image_2_rotate=\u00bbnone\u00bb image_2_scale=\u00bb1&#8243; image_2_animation=\u00bbGrow In\u00bb image_2_padding=\u00bbauto\u00bb image_2_box_shadow=\u00bbx_large_depth\u00bb image_2_max_width_desktop=\u00bb100%\u00bb image_2_max_width_mobile=\u00bb100%\u00bb image_2_image_width_mobile=\u00bbdefault\u00bb image_3_offset_x_sign=\u00bb+\u00bb image_3_offset_x=\u00bb0%\u00bb image_3_offset_y_sign=\u00bb+\u00bb image_3_offset_y=\u00bb0%\u00bb image_3_rotate_sign=\u00bb+\u00bb image_3_rotate=\u00bbnone\u00bb image_3_scale=\u00bb1&#8243; image_3_animation=\u00bbFade In\u00bb image_3_padding=\u00bbauto\u00bb image_3_box_shadow=\u00bbnone\u00bb image_3_max_width_desktop=\u00bb100%\u00bb image_3_max_width_mobile=\u00bb100%\u00bb image_3_image_width_mobile=\u00bbdefault\u00bb image_4_offset_x_sign=\u00bb+\u00bb image_4_offset_x=\u00bb0%\u00bb image_4_offset_y_sign=\u00bb+\u00bb image_4_offset_y=\u00bb0%\u00bb image_4_rotate_sign=\u00bb+\u00bb image_4_rotate=\u00bbnone\u00bb image_4_scale=\u00bb1&#8243; image_4_animation=\u00bbFade In\u00bb image_4_padding=\u00bbauto\u00bb image_4_box_shadow=\u00bbnone\u00bb image_4_max_width_desktop=\u00bb100%\u00bb image_4_max_width_mobile=\u00bb100%\u00bb image_4_image_width_mobile=\u00bbdefault\u00bb element_sizing=\u00bbdefault\u00bb image_loading=\u00bbdefault\u00bb border_radius=\u00bbnone\u00bb overflow=\u00bbvisible\u00bb][\/vc_column][vc_column column_padding=\u00bbpadding-4-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_animated_title heading_tag=\u00bbh6&#8243; style=\u00bbcolor-strip-reveal\u00bb color=\u00bbExtra-Color-1&#8243; text=\u00bbGarant\u00eda de calidad\u00bb][vc_column_text]\n<h2>Marcas<\/h2>\n[\/vc_column_text][vc_column_text css=\u00bb.vc_custom_1626210760781{margin-top: 20px !important;}\u00bb]Trabajamos con las mejores marcas de maquinaria pesada y equipos para cada actividad espec\u00edfica.<\/p>\n<p>Hacemos uso de solo marcas con prestigio en el mercado, gracias a su tecnolog\u00eda la productividad en sus proyectos incremente.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#fcd200&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb5%\u00bb bottom_padding=\u00bb5%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb id=\u00bbContactenos\u00bb row_name=\u00bbCont\u00e1ctenos\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb100&#8243;][nectar_highlighted_text color_type=\u00bbregular\u00bb highlight_color=\u00bb#f59b1a\u00bb text_color=\u00bb#000000&#8243; style=\u00bbfull_text\u00bb highlight_expansion=\u00bbdefault\u00bb]\n<h2>Clientes que han confiado en Geoexcon<\/h2>\n[\/nectar_highlighted_text][divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb30&#8243;]<div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-cog\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"extra-color-3\" data-spacing=\"default\" data-alignment=\"left\"> \n<ul>\n<li>Cer\u00e1micas de Antioquia<\/li>\n<li>Mej\u00eda Acevedo<\/li>\n<li>Arquitectos e Ingenieros Asociados (AIA)<\/li>\n<li>Ingeomega<\/li>\n<li>Uni\u00f3n temporal Mej\u00eda Acevedo SYE<\/li>\n<li>Volmaco SAS<\/li>\n<li>Invertrans Grupo empresarial SAS<\/li>\n<\/ul>\n <\/div>[image_with_animation image_url=\u00bb2449&#8243; animation=\u00bbFade In\u00bb hover_animation=\u00bbnone\u00bb alignment=\u00bb\u00bb border_radius=\u00bbnone\u00bb box_shadow=\u00bbnone\u00bb image_loading=\u00bbdefault\u00bb max_width=\u00bb100%\u00bb max_width_mobile=\u00bbdefault\u00bb][nectar_highlighted_text color_type=\u00bbregular\u00bb style=\u00bbfull_text\u00bb highlight_expansion=\u00bbdefault\u00bb]\n<h3>Queremos ser tu colaborador de confianza, diligencia el formulario.<\/h3>\n[\/nectar_highlighted_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb100&#8243;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2405-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"2405\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/2312#wpcf7-f2405-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"2405\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.3\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2405-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> Tu nombre<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Tu correo electr\u00f3nico<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Tel\u00e9fono<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-669\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-669\" \/><\/span><\/label>\n<\/p>\n<p><label> Asunto<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Tu mensaje (opcional)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb-100&#8243;][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_spacing=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/5&#8243; tablet_width_inherit=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#03212d\u00bb video_bg=\u00bbuse_video\u00bb video_mp4=\u00bbhttp:\/\/geoexcon.com\/wp-content\/uploads\/2025\/11\/Geoexcon-maquinaria.mp4&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb8%\u00bb bottom_padding=\u00bb8%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb id=\u00bbintro\u00bb row_name=\u00bbGeoexcon\u00bb color_overlay=\u00bb#5c6971&#8243; overlay_strength=\u00bb0.5&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbtop-bottom\u00bb column_element_spacing=\u00bbdefault\u00bb&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-2312","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Home - Geoexcon soluciones maquinaria y equipos - Geoexcon | Excavaciones y Construcci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/geoexcon.com\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - Geoexcon soluciones maquinaria y equipos - Geoexcon | Excavaciones y Construcci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#03212d\u00bb video_bg=\u00bbuse_video\u00bb video_mp4=\u00bbhttp:\/\/geoexcon.com\/wp-content\/uploads\/2025\/11\/Geoexcon-maquinaria.mp4&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb8%\u00bb bottom_padding=\u00bb8%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb id=\u00bbintro\u00bb row_name=\u00bbGeoexcon\u00bb color_overlay=\u00bb#5c6971&#8243; overlay_strength=\u00bb0.5&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbtop-bottom\u00bb column_element_spacing=\u00bbdefault\u00bb...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/geoexcon.com\/\" \/>\n<meta property=\"og:site_name\" content=\"Geoexcon | Excavaciones y Construcci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Geoexcon\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-17T01:05:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/geoexcon.com\/\",\"url\":\"https:\/\/geoexcon.com\/\",\"name\":\"Home - Geoexcon soluciones maquinaria y equipos - Geoexcon | Excavaciones y Construcci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/geoexcon.com\/#website\"},\"datePublished\":\"2016-07-20T17:39:33+00:00\",\"dateModified\":\"2025-11-17T01:05:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/geoexcon.com\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/geoexcon.com\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/geoexcon.com\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/geoexcon.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home &#8211; Geoexcon soluciones maquinaria y equipos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/geoexcon.com\/#website\",\"url\":\"https:\/\/geoexcon.com\/\",\"name\":\"Geoexcon | Excavaciones y Construcci\u00f3n\",\"description\":\"Incremente su productuvidad en proyectos de construci\u00f3n\",\"publisher\":{\"@id\":\"https:\/\/geoexcon.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/geoexcon.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/geoexcon.com\/#organization\",\"name\":\"Geoexcon | Excavaciones y Construcci\u00f3n\",\"url\":\"https:\/\/geoexcon.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/geoexcon.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/geoexcon.com\/wp-content\/uploads\/2021\/07\/geoexcon-excavaciones-construccion-min-2.jpg\",\"contentUrl\":\"https:\/\/geoexcon.com\/wp-content\/uploads\/2021\/07\/geoexcon-excavaciones-construccion-min-2.jpg\",\"width\":900,\"height\":700,\"caption\":\"Geoexcon | Excavaciones y Construcci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/geoexcon.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Geoexcon\",\"https:\/\/www.instagram.com\/geoexcon\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - Geoexcon soluciones maquinaria y equipos - Geoexcon | Excavaciones y Construcci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/geoexcon.com\/","og_locale":"es_ES","og_type":"article","og_title":"Home - Geoexcon soluciones maquinaria y equipos - Geoexcon | Excavaciones y Construcci\u00f3n","og_description":"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#03212d\u00bb video_bg=\u00bbuse_video\u00bb video_mp4=\u00bbhttp:\/\/geoexcon.com\/wp-content\/uploads\/2025\/11\/Geoexcon-maquinaria.mp4&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb8%\u00bb bottom_padding=\u00bb8%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb id=\u00bbintro\u00bb row_name=\u00bbGeoexcon\u00bb color_overlay=\u00bb#5c6971&#8243; overlay_strength=\u00bb0.5&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bbtop-bottom\u00bb column_element_spacing=\u00bbdefault\u00bb...","og_url":"https:\/\/geoexcon.com\/","og_site_name":"Geoexcon | Excavaciones y Construcci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/Geoexcon","article_modified_time":"2025-11-17T01:05:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/geoexcon.com\/","url":"https:\/\/geoexcon.com\/","name":"Home - Geoexcon soluciones maquinaria y equipos - Geoexcon | Excavaciones y Construcci\u00f3n","isPartOf":{"@id":"https:\/\/geoexcon.com\/#website"},"datePublished":"2016-07-20T17:39:33+00:00","dateModified":"2025-11-17T01:05:47+00:00","breadcrumb":{"@id":"https:\/\/geoexcon.com\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/geoexcon.com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/geoexcon.com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/geoexcon.com\/"},{"@type":"ListItem","position":2,"name":"Home &#8211; Geoexcon soluciones maquinaria y equipos"}]},{"@type":"WebSite","@id":"https:\/\/geoexcon.com\/#website","url":"https:\/\/geoexcon.com\/","name":"Geoexcon | Excavaciones y Construcci\u00f3n","description":"Incremente su productuvidad en proyectos de construci\u00f3n","publisher":{"@id":"https:\/\/geoexcon.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/geoexcon.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/geoexcon.com\/#organization","name":"Geoexcon | Excavaciones y Construcci\u00f3n","url":"https:\/\/geoexcon.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/geoexcon.com\/#\/schema\/logo\/image\/","url":"https:\/\/geoexcon.com\/wp-content\/uploads\/2021\/07\/geoexcon-excavaciones-construccion-min-2.jpg","contentUrl":"https:\/\/geoexcon.com\/wp-content\/uploads\/2021\/07\/geoexcon-excavaciones-construccion-min-2.jpg","width":900,"height":700,"caption":"Geoexcon | Excavaciones y Construcci\u00f3n"},"image":{"@id":"https:\/\/geoexcon.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Geoexcon","https:\/\/www.instagram.com\/geoexcon"]}]}},"_links":{"self":[{"href":"https:\/\/geoexcon.com\/index.php\/wp-json\/wp\/v2\/pages\/2312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/geoexcon.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/geoexcon.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/geoexcon.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/geoexcon.com\/index.php\/wp-json\/wp\/v2\/comments?post=2312"}],"version-history":[{"count":69,"href":"https:\/\/geoexcon.com\/index.php\/wp-json\/wp\/v2\/pages\/2312\/revisions"}],"predecessor-version":[{"id":2465,"href":"https:\/\/geoexcon.com\/index.php\/wp-json\/wp\/v2\/pages\/2312\/revisions\/2465"}],"wp:attachment":[{"href":"https:\/\/geoexcon.com\/index.php\/wp-json\/wp\/v2\/media?parent=2312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}